{"id":286,"date":"2025-06-30T13:26:35","date_gmt":"2025-06-30T11:26:35","guid":{"rendered":"https:\/\/eventsoffice.com\/?post_type=feature&#038;p=286"},"modified":"2025-07-03T18:11:10","modified_gmt":"2025-07-03T16:11:10","slug":"canali-di-vendita-extra","status":"publish","type":"feature","link":"https:\/\/eventsoffice.com\/it\/feature\/extra-sales-channels\/","title":{"rendered":"Canali di vendita extra"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Trasformate i vostri studenti in fan fedeli offrendo pi\u00f9 di un semplice corso. Vendete facilmente merchandising, lezioni private o altri servizi extra direttamente dalla cassa dell'evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Che si tratti di una maglietta brandizzata, di una cena post-workshop o di un alloggio speciale per un ritiro di danza, il semplice sistema di inventario della nostra piattaforma vi aiuta a gestire e a mantenere le vostre promesse, creando ulteriori flussi di entrate per la vostra scuola di danza.<\/p>\n\n\n<style>.wp-block-kadence-image.kb-image286_1ee891-ce:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-xl, 4rem);margin-bottom:var(--global-kb-spacing-xl, 4rem);}.kb-image286_1ee891-ce:not(.kb-image-is-ratio-size) .kb-img, .kb-image286_1ee891-ce.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image286_1ee891-ce .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;}.kb-image286_1ee891-ce img.kb-img, .kb-image286_1ee891-ce .kb-img img{border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}<\/style>\n<figure class=\"wp-block-kadence-image kb-image286_1ee891-ce size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-1024x640.jpg\" alt=\"Schermata della funzione vendite extra\" class=\"kb-img wp-image-759\" srcset=\"https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-1024x640.jpg 1024w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-300x188.jpg 300w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-768x480.jpg 768w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-1536x960.jpg 1536w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-2048x1280.jpg 2048w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-18x12.jpg 18w, https:\/\/eventsoffice.com\/wp-content\/uploads\/2025\/07\/extra-feature-screenshot-1320x825.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"featured_media":750,"parent":0,"template":"","meta":{"_acf_changed":true},"class_list":["post-286","feature","type-feature","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eventsoffice.com\/it\/wp-json\/wp\/v2\/feature\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventsoffice.com\/it\/wp-json\/wp\/v2\/feature"}],"about":[{"href":"https:\/\/eventsoffice.com\/it\/wp-json\/wp\/v2\/types\/feature"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventsoffice.com\/it\/wp-json\/wp\/v2\/media\/750"}],"wp:attachment":[{"href":"https:\/\/eventsoffice.com\/it\/wp-json\/wp\/v2\/media?parent=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}